{"id":24441,"date":"2024-04-16T18:01:58","date_gmt":"2024-04-16T16:01:58","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/"},"modified":"2024-04-16T18:01:58","modified_gmt":"2024-04-16T16:01:58","slug":"federcanottaggio-e-sociale-binomio-vincente","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/","title":{"rendered":"Federcanottaggio e sociale, binomio vincente"},"content":{"rendered":"<p>    <video-js id=\"videojs6a0499ed0f958\" class=\"vjs-big-play-centered\" controls preload=\"auto\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/video.italpress.com\/play\/mp4\/video\/8WK2\" type=\"video\/mp4\" \/>\r\n    <\/video-js>\r\n           <br \/>\n<\/p>\n<div> ROMA (ITALPRESS) &#8211; La Federcanottaggio rilancia anche per il 2024 il proprio impegno nel sociale. Presso la sala conferenze del palazzo delle federazioni a Roma, sono state illustrate le attivit\u00e0 introdotte per il 2024 dall&#8217;area Canottaggio Sociale della Federazione italiana Canottaggio. Tra le molteplici iniziative, che interessano i vari territori, l&#8217;individuazione di Hub nei quali sviluppare il servizio relativo al progetto &#8220;Sport Terapia Integrata&#8221; in favore delle persone che hanno avuto patologie oncologiche al seno e la prosecuzione dei progetti &#8220;#StudiEremoinFamiglia&#8221; e &#8220;Remare in Libert\u00e0&#8221;, finanziati dal Dipartimento dello Sport della Presidenza del Consiglio dei ministri e da Sport e Salute. <br \/>\nspf\/gm\/gtr<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) &#8211; La Federcanottaggio rilancia anche per il 2024 il proprio impegno nel sociale. Presso la sala conferenze del palazzo delle federazioni a Roma, sono state illustrate le attivit\u00e0 introdotte per il 2024 dall&#8217;area Canottaggio Sociale della Federazione italiana Canottaggio. Tra le molteplici iniziative, che interessano i vari territori, l&#8217;individuazione di Hub nei quali [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":24442,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1171],"tags":[],"class_list":["post-24441","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-video","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Federcanottaggio e sociale, binomio vincente - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Federcanottaggio e sociale, binomio vincente - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) &#8211; La Federcanottaggio rilancia anche per il 2024 il proprio impegno nel sociale. Presso la sala conferenze del palazzo delle federazioni a Roma, sono state illustrate le attivit\u00e0 introdotte per il 2024 dall&#8217;area Canottaggio Sociale della Federazione italiana Canottaggio. Tra le molteplici iniziative, che interessano i vari territori, l&#8217;individuazione di Hub nei quali [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-16T16:01:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/16\\\/federcanottaggio-e-sociale-binomio-vincente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/16\\\/federcanottaggio-e-sociale-binomio-vincente\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Federcanottaggio e sociale, binomio vincente\",\"datePublished\":\"2024-04-16T16:01:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/16\\\/federcanottaggio-e-sociale-binomio-vincente\\\/\"},\"wordCount\":120,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/16\\\/federcanottaggio-e-sociale-binomio-vincente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/8WK2.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/16\\\/federcanottaggio-e-sociale-binomio-vincente\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/16\\\/federcanottaggio-e-sociale-binomio-vincente\\\/\",\"name\":\"Federcanottaggio e sociale, binomio vincente - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/16\\\/federcanottaggio-e-sociale-binomio-vincente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/16\\\/federcanottaggio-e-sociale-binomio-vincente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/8WK2.jpg\",\"datePublished\":\"2024-04-16T16:01:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/16\\\/federcanottaggio-e-sociale-binomio-vincente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/16\\\/federcanottaggio-e-sociale-binomio-vincente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/16\\\/federcanottaggio-e-sociale-binomio-vincente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/8WK2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/8WK2.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/16\\\/federcanottaggio-e-sociale-binomio-vincente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Federcanottaggio e sociale, binomio vincente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Federcanottaggio e sociale, binomio vincente - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/","og_locale":"it_IT","og_type":"article","og_title":"Federcanottaggio e sociale, binomio vincente - Live Magazine","og_description":"ROMA (ITALPRESS) &#8211; La Federcanottaggio rilancia anche per il 2024 il proprio impegno nel sociale. Presso la sala conferenze del palazzo delle federazioni a Roma, sono state illustrate le attivit\u00e0 introdotte per il 2024 dall&#8217;area Canottaggio Sociale della Federazione italiana Canottaggio. Tra le molteplici iniziative, che interessano i vari territori, l&#8217;individuazione di Hub nei quali [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-04-16T16:01:58+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Federcanottaggio e sociale, binomio vincente","datePublished":"2024-04-16T16:01:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/"},"wordCount":120,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/04\/8WK2.jpg","articleSection":["Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/","name":"Federcanottaggio e sociale, binomio vincente - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/04\/8WK2.jpg","datePublished":"2024-04-16T16:01:58+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/04\/8WK2.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/04\/8WK2.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/16\/federcanottaggio-e-sociale-binomio-vincente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Federcanottaggio e sociale, binomio vincente"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/04\/8WK2.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/24441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=24441"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/24441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/24442"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=24441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=24441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=24441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}