{"id":24333,"date":"2024-04-15T21:00:45","date_gmt":"2024-04-15T19:00:45","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/"},"modified":"2024-04-15T21:00:45","modified_gmt":"2024-04-15T19:00:45","slug":"a-new-york-si-apre-lo-storico-processo-contro-trump","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/","title":{"rendered":"A New York si apre lo storico processo contro Trump"},"content":{"rendered":"<p>    <video-js id=\"videojs6a047caa1452e\" class=\"vjs-big-play-centered\" controls preload=\"auto\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/video.italpress.com\/play\/mp4\/video\/Gzzr\" type=\"video\/mp4\" \/>\r\n    <\/video-js>\r\n           <br \/>\n<\/p>\n<div> NEW YORK (ITALPRESS) &#8211; Giornata storica a New York e per tutti gli Stati Uniti. A Manhattan si \u00e8 aperto il processo penale contro Donald Trump, quello soprannominato &#8220;Hush Money&#8221; (&#8220;Soldi per il silenzio&#8221;), nel quale l&#8217;ex presidente \u00e8 accusato di aver pagato nel 2016, alla vigilia delle elezioni che lo elessero alla Casa Bianca, la pornostar Stormy Daniels per nascondere la relazione che avrebbe avuto con lei dieci anni prima.<br \/>\nL&#8217;accusa, guidata dal procuratore di Manhattan Alvin Grabb, sostiene che l&#8217;attrice fu pagata con 130 mila dollari anticipati dall&#8217;avvocato di Trump Michael Cohen (ora tra i maggiori testimoni dell&#8217;accusa) poi restituiti falsificando documenti contabili della societ\u00e0 immobiliare di Trump.  Il processo \u00e8 storico perch\u00e9 mai un ex presidente nella storia degli Stati Uniti era stato messo alla sbarra in un procedimento penale in cui rischia fino a 4 anni di galera. Secondo Trump si tratta di una manovra politica escogitata dall&#8217;amministrazione Biden. Entrando in tribunale, l&#8217;ex presidente ha parlato di &#8220;aggressione all&#8217;America. Ed \u00e8 per questo che sono molto orgoglioso di essere qui oggi. \u00c8 un&#8217;aggressione al nostro Paese, un Paese che sta fallendo&#8230; Questo \u00e8  un attacco politico&#8221;, ha aggiunto.<br \/>\nIl processo si apre con la selezione della giuria, gli avvocati di Trump e l&#8217;accusa dovranno selezionare 12 cittadini di Manhattan (notoriamente democratica) tra centinaia che sono stati chiamati. Fuori dall&#8217;aula, televisioni e giornalisti di tutto il mondo, che erano molti di pi\u00f9 di una piccola folla di simpatizzanti &#8220;Make America Great Again&#8221;, che con le loro bandiere di supporto per Trump, hanno gridato i loro slogan senza creare problemi alle forze di polizia.<\/p>\n<p>xo9\/sat\/gsl (Video di Stefano Vaccara)<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>NEW YORK (ITALPRESS) &#8211; Giornata storica a New York e per tutti gli Stati Uniti. A Manhattan si \u00e8 aperto il processo penale contro Donald Trump, quello soprannominato &#8220;Hush Money&#8221; (&#8220;Soldi per il silenzio&#8221;), nel quale l&#8217;ex presidente \u00e8 accusato di aver pagato nel 2016, alla vigilia delle elezioni che lo elessero alla Casa Bianca, [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":24334,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1171],"tags":[],"class_list":["post-24333","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-video","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A New York si apre lo storico processo contro Trump - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A New York si apre lo storico processo contro Trump - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"NEW YORK (ITALPRESS) &#8211; Giornata storica a New York e per tutti gli Stati Uniti. A Manhattan si \u00e8 aperto il processo penale contro Donald Trump, quello soprannominato &#8220;Hush Money&#8221; (&#8220;Soldi per il silenzio&#8221;), nel quale l&#8217;ex presidente \u00e8 accusato di aver pagato nel 2016, alla vigilia delle elezioni che lo elessero alla Casa Bianca, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-15T19:00:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/15\\\/a-new-york-si-apre-lo-storico-processo-contro-trump\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/15\\\/a-new-york-si-apre-lo-storico-processo-contro-trump\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"A New York si apre lo storico processo contro Trump\",\"datePublished\":\"2024-04-15T19:00:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/15\\\/a-new-york-si-apre-lo-storico-processo-contro-trump\\\/\"},\"wordCount\":295,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/15\\\/a-new-york-si-apre-lo-storico-processo-contro-trump\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Gzzr.jpg\",\"articleSection\":[\"Video\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/15\\\/a-new-york-si-apre-lo-storico-processo-contro-trump\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/15\\\/a-new-york-si-apre-lo-storico-processo-contro-trump\\\/\",\"name\":\"A New York si apre lo storico processo contro Trump - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/15\\\/a-new-york-si-apre-lo-storico-processo-contro-trump\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/15\\\/a-new-york-si-apre-lo-storico-processo-contro-trump\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Gzzr.jpg\",\"datePublished\":\"2024-04-15T19:00:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/15\\\/a-new-york-si-apre-lo-storico-processo-contro-trump\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/15\\\/a-new-york-si-apre-lo-storico-processo-contro-trump\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/15\\\/a-new-york-si-apre-lo-storico-processo-contro-trump\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Gzzr.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Gzzr.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/15\\\/a-new-york-si-apre-lo-storico-processo-contro-trump\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A New York si apre lo storico processo contro Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A New York si apre lo storico processo contro Trump - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/","og_locale":"it_IT","og_type":"article","og_title":"A New York si apre lo storico processo contro Trump - Live Magazine","og_description":"NEW YORK (ITALPRESS) &#8211; Giornata storica a New York e per tutti gli Stati Uniti. A Manhattan si \u00e8 aperto il processo penale contro Donald Trump, quello soprannominato &#8220;Hush Money&#8221; (&#8220;Soldi per il silenzio&#8221;), nel quale l&#8217;ex presidente \u00e8 accusato di aver pagato nel 2016, alla vigilia delle elezioni che lo elessero alla Casa Bianca, [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-04-15T19:00:45+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"A New York si apre lo storico processo contro Trump","datePublished":"2024-04-15T19:00:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/"},"wordCount":295,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/04\/Gzzr.jpg","articleSection":["Video"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/","name":"A New York si apre lo storico processo contro Trump - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/04\/Gzzr.jpg","datePublished":"2024-04-15T19:00:45+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/04\/Gzzr.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/04\/Gzzr.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/15\/a-new-york-si-apre-lo-storico-processo-contro-trump\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"A New York si apre lo storico processo contro Trump"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/04\/Gzzr.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/24333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=24333"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/24333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/24334"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=24333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=24333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=24333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}