{"id":24241,"date":"2024-04-14T21:00:56","date_gmt":"2024-04-14T19:00:56","guid":{"rendered":"https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/"},"modified":"2024-04-14T21:00:56","modified_gmt":"2024-04-14T19:00:56","slug":"missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente","status":"publish","type":"post","link":"https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/","title":{"rendered":"Missili e droni iraniani su Israele, notte di guerra in Medioriente"},"content":{"rendered":"<div>\n<p>ROMA (ITALPRESS) \u2013 E\u2019 stata una notte di guerra, con tre ondate di droni e missili lanciati da Teheran contro Israele. Un attacco massiccio condotto con la tecnica della saturazione: massima concentrazione di vettori in maniera da rendere problematica l\u2019intercettazione difensiva. La risposta delle difese israeliane ha consentito di limitare i danni e di intercettare la quasi totalit\u00e0 di droni e missili. Secondo fonti israeliane l\u2019attacco avrebbe provocato solo feriti tra i civili, tra cui una bimba di sette anni.<\/p>\n<p>\u201cQuello che accadr\u00e0 dopo sar\u00e0 il momento pi\u00f9 pericoloso in Medio Oriente dal 1973\u201d prevedono gli analisti di strategie militari, che temono una sorta di ping \u2013 pong bellico, un botta e risposta in crescendo. Per prevenire una escalation incontrollata nei giorni scorsi il segretario di Stato statunitense, Antony Blinken, ha parlato con Arabia Saudita, Cina, Turchia. Mentre da parte iraniana sono partite telefonate verso Arabia Saudita, Regno Unito, Germania, Turchia. Dall\u2019evoluzione della situazione e dall\u2019 eventuale ampliamento del conflitto dipende anche il coinvolgimento indiretto dell\u2019 Italia, in quanto baricentro mediterraneo delle basi Usa.<\/p>\n<p>\u201cL\u2019Italia rimane in prima linea, anche come presidenza G7, per evitare un allargamento del conflitto in Medio Oriente, per abbassare la tensione e per facilitare il dialogo. Questo che viviamo \u00e8 un momento decisivo per ritornare a una dinamica di pace nella regione\u201d, afferma una nota della Farnesina.<\/p>\n<p>Una riunione d\u2019urgenza del Consiglio di sicurezza delle Nazioni Unite si terr\u00e0 alle 22 ora italiana dopo l\u2019attacco dell\u2019Iran a Israele.<\/p>\n<p>La convocazione \u00e8 stata confermata dall\u2019ambasciatrice maltese all\u2019ONU Vanessa Frazier. Malta attualmente presiede il Consiglio di Sicurezza.<br \/>\nFrazier ha affermato che l\u2019incontro \u00e8 stato richiesto da Israele. In una lettera al presidente del Consiglio di Sicurezza, Tel Aviv afferma che gli attacchi \u201crappresentano una grave minaccia alla pace e alla sicurezza internazionale\u201d.<br \/>\nLa lettera accusa l\u2019Iran di violare i suoi obblighi internazionali e di essere \u201cl\u2019architetto dell\u2019instabilit\u00e0 da anni\u201d attraverso il suo sostegno ad Hamas a Gaza, a Hezbollah in Libano e agli Houthi nello Yemen.<br \/>\n\u201cLa gravit\u00e0 e il volume degli attacchi non hanno precedenti\u201d, aggiunge la lettera, \u201ce costituiscono una flagrante violazione della sovranit\u00e0 di Israele, del diritto internazionale e delle risoluzioni del Consiglio di Sicurezza\u201d.<br \/>\nIn una lettera indirizzata a Frazier, l\u2019Iran si \u00e8 difeso, affermando di aver agito \u201cper legittima difesa, come delineato nell\u2019articolo 51 della Carta delle Nazioni Unite, e in risposta alla ricorrente aggressione militare di Israele\u201d.<\/p>\n<p>\u2013 foto Agenzia IPA \u2013<\/p>\n<p>(ITALPRESS).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (ITALPRESS) \u2013 E\u2019 stata una notte di guerra, con tre ondate di droni e missili lanciati da Teheran contro Israele. Un attacco massiccio condotto con la tecnica della saturazione: massima concentrazione di vettori in maniera da rendere problematica l\u2019intercettazione difensiva. La risposta delle difese israeliane ha consentito di limitare i danni e di intercettare [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":24242,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1129],"tags":[],"class_list":["post-24241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mondo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Missili e droni iraniani su Israele, notte di guerra in Medioriente - Live Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Missili e droni iraniani su Israele, notte di guerra in Medioriente - Live Magazine\" \/>\n<meta property=\"og:description\" content=\"ROMA (ITALPRESS) \u2013 E\u2019 stata una notte di guerra, con tre ondate di droni e missili lanciati da Teheran contro Israele. Un attacco massiccio condotto con la tecnica della saturazione: massima concentrazione di vettori in maniera da rendere problematica l\u2019intercettazione difensiva. La risposta delle difese israeliane ha consentito di limitare i danni e di intercettare [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/\" \/>\n<meta property=\"og:site_name\" content=\"Live Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveMag\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-14T19:00:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"italpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:site\" content=\"@LiveNotizie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"italpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/14\\\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/14\\\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\\\/\"},\"author\":{\"name\":\"italpress\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\"},\"headline\":\"Missili e droni iraniani su Israele, notte di guerra in Medioriente\",\"datePublished\":\"2024-04-14T19:00:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/14\\\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\\\/\"},\"wordCount\":417,\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/14\\\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IPA_Agency_IPA45135053.jpg\",\"articleSection\":[\"Mondo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/14\\\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/14\\\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\\\/\",\"name\":\"Missili e droni iraniani su Israele, notte di guerra in Medioriente - Live Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/14\\\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/14\\\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IPA_Agency_IPA45135053.jpg\",\"datePublished\":\"2024-04-14T19:00:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/14\\\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/14\\\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/14\\\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IPA_Agency_IPA45135053.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IPA_Agency_IPA45135053.jpg\",\"width\":1620,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/2024\\\/04\\\/14\\\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.livemag.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Missili e droni iraniani su Israele, notte di guerra in Medioriente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#website\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"name\":\"Live Magazine\",\"description\":\"Varie ed eventi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.livemag.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#organization\",\"name\":\"LiveMag\",\"alternateName\":\"LiveMag News ed eventi\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.livemag.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/immagine-sito.jpg\",\"width\":696,\"height\":696,\"caption\":\"LiveMag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveMag\\\/\",\"https:\\\/\\\/x.com\\\/LiveNotizie\",\"https:\\\/\\\/www.instagram.com\\\/livemag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.livemag.it\\\/#\\\/schema\\\/person\\\/b62c5f44451fdcdaeb0afe6c2424e73c\",\"name\":\"italpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g\",\"caption\":\"italpress\"},\"description\":\"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.\",\"url\":\"https:\\\/\\\/www.livemag.it\\\/index.php\\\/author\\\/italpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Missili e droni iraniani su Israele, notte di guerra in Medioriente - Live Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/","og_locale":"it_IT","og_type":"article","og_title":"Missili e droni iraniani su Israele, notte di guerra in Medioriente - Live Magazine","og_description":"ROMA (ITALPRESS) \u2013 E\u2019 stata una notte di guerra, con tre ondate di droni e missili lanciati da Teheran contro Israele. Un attacco massiccio condotto con la tecnica della saturazione: massima concentrazione di vettori in maniera da rendere problematica l\u2019intercettazione difensiva. La risposta delle difese israeliane ha consentito di limitare i danni e di intercettare [&hellip;]","og_url":"https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/","og_site_name":"Live Magazine","article_publisher":"https:\/\/www.facebook.com\/LiveMag\/","article_published_time":"2024-04-14T19:00:56+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/ograph.jpg","type":"image\/jpeg"}],"author":"italpress","twitter_card":"summary_large_image","twitter_creator":"@LiveNotizie","twitter_site":"@LiveNotizie","twitter_misc":{"Scritto da":"italpress","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/#article","isPartOf":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/"},"author":{"name":"italpress","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c"},"headline":"Missili e droni iraniani su Israele, notte di guerra in Medioriente","datePublished":"2024-04-14T19:00:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/"},"wordCount":417,"publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/04\/IPA_Agency_IPA45135053.jpg","articleSection":["Mondo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/","url":"https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/","name":"Missili e droni iraniani su Israele, notte di guerra in Medioriente - Live Magazine","isPartOf":{"@id":"https:\/\/www.livemag.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/#primaryimage"},"image":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/04\/IPA_Agency_IPA45135053.jpg","datePublished":"2024-04-14T19:00:56+00:00","breadcrumb":{"@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/#primaryimage","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/04\/IPA_Agency_IPA45135053.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/04\/IPA_Agency_IPA45135053.jpg","width":1620,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.livemag.it\/index.php\/2024\/04\/14\/missili-e-droni-iraniani-su-israele-notte-di-guerra-in-medioriente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.livemag.it\/"},{"@type":"ListItem","position":2,"name":"Missili e droni iraniani su Israele, notte di guerra in Medioriente"}]},{"@type":"WebSite","@id":"https:\/\/www.livemag.it\/#website","url":"https:\/\/www.livemag.it\/","name":"Live Magazine","description":"Varie ed eventi","publisher":{"@id":"https:\/\/www.livemag.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.livemag.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.livemag.it\/#organization","name":"LiveMag","alternateName":"LiveMag News ed eventi","url":"https:\/\/www.livemag.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","contentUrl":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/02\/immagine-sito.jpg","width":696,"height":696,"caption":"LiveMag"},"image":{"@id":"https:\/\/www.livemag.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveMag\/","https:\/\/x.com\/LiveNotizie","https:\/\/www.instagram.com\/livemag\/"]},{"@type":"Person","@id":"https:\/\/www.livemag.it\/#\/schema\/person\/b62c5f44451fdcdaeb0afe6c2424e73c","name":"italpress","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6a21695fc713ce7ee312cf57c97e2e641feb365be72d8745574d3c3e2b59066?s=96&r=g","caption":"italpress"},"description":"Italpress \u00e8 un'agenzia di stampa italiana a carattere nazionale.","url":"https:\/\/www.livemag.it\/index.php\/author\/italpress\/"}]}},"jetpack_featured_media_url":"https:\/\/www.livemag.it\/wp-content\/uploads\/2024\/04\/IPA_Agency_IPA45135053.jpg","_links":{"self":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/24241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/comments?post=24241"}],"version-history":[{"count":0,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/posts\/24241\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media\/24242"}],"wp:attachment":[{"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/media?parent=24241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/categories?post=24241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.livemag.it\/index.php\/wp-json\/wp\/v2\/tags?post=24241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}